{"id":1443,"date":"2021-06-19T17:18:24","date_gmt":"2021-06-19T15:18:24","guid":{"rendered":"https:\/\/www.andreas-mehltretter.de\/wp\/?p=1443"},"modified":"2021-06-19T17:18:24","modified_gmt":"2021-06-19T15:18:24","slug":"mit-dem-mietrecht-mieterinnen-staerken-und-entlasten","status":"publish","type":"post","link":"https:\/\/www.andreas-mehltretter.de\/archiv\/2021\/06\/mit-dem-mietrecht-mieterinnen-staerken-und-entlasten\/","title":{"rendered":"Mit dem Mietrecht Mieter*innen st\u00e4rken und entlasten"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Bericht zur Online-Veranstaltung am 16. Juni 2021<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-medium\"><a href=\"https:\/\/www.andreas-mehltretter.de\/wp\/wp-content\/uploads\/2021\/06\/2021-06-16-Mieten-Veranstaltung-Bericht-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.andreas-mehltretter.de\/wp\/wp-content\/uploads\/2021\/06\/2021-06-16-Mieten-Veranstaltung-Bericht-300x300.jpg\" alt=\"\" class=\"wp-image-1444\" srcset=\"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-content\/uploads\/2021\/06\/2021-06-16-Mieten-Veranstaltung-Bericht-300x300.jpg 300w, https:\/\/www.andreas-mehltretter.de\/archiv\/wp-content\/uploads\/2021\/06\/2021-06-16-Mieten-Veranstaltung-Bericht-1024x1024.jpg 1024w, https:\/\/www.andreas-mehltretter.de\/archiv\/wp-content\/uploads\/2021\/06\/2021-06-16-Mieten-Veranstaltung-Bericht-150x150.jpg 150w, https:\/\/www.andreas-mehltretter.de\/archiv\/wp-content\/uploads\/2021\/06\/2021-06-16-Mieten-Veranstaltung-Bericht-768x768.jpg 768w, https:\/\/www.andreas-mehltretter.de\/archiv\/wp-content\/uploads\/2021\/06\/2021-06-16-Mieten-Veranstaltung-Bericht-1536x1536.jpg 1536w, https:\/\/www.andreas-mehltretter.de\/archiv\/wp-content\/uploads\/2021\/06\/2021-06-16-Mieten-Veranstaltung-Bericht-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Als SPD im Bundeswahlkreis Freising-Pfaffenhofen-Schrobenhausen hatten wir zur Diskussion dar\u00fcber eingeladen, wie wir Mieter*innen st\u00e4rken wollen. Denn im M\u00fcnchner Speckg\u00fcrtel, aber auch in den l\u00e4ndlicheren Gebieten Oberbayerns steigen die Mieten immer weiter, Eigenbedarfsk\u00fcndigungen und Luxussanierungen machen so manchem Mieter das Leben schwer. Dabei ist Wohnen ein Menschenrecht, das niemanden in finanzielle Schwierigkeiten bringen darf. Mitunter wurde die Diskussion angesto\u00dfen durch die Impulse von Michael Gro\u00df, welcher SPD-Bundestagsabgeordneter und Experte f\u00fcr Mietrecht ist, als auch Stefanie Buchner-Joppich von der Wohnungsnotfallhilfe der Caritas Schrobenhausen. Moderiert wurde der Abend von dem Bundestagskandidaten des Bundeswahlkreises 214 Freising-Pfaffenhofen-Schrobenhausen, Andreas Mehltretter aus Freising. Diskutiert wurde mit dem Publikum \u00fcber die Problemlage der Mieter*innen und wie die SPD sie mit Mietpreisbremse, Mietspiegel und Mietenmoratorium sch\u00fctzen will.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit der Frage: \u201cWie k\u00f6nnen wir Wohnen f\u00fcr alle erm\u00f6glichen?\u201d, er\u00f6ffnete Andreas Mehltretter die Veranstaltung, worauf er die beiden G\u00e4ste vorstellte. Michael Gro\u00df ist Bundestagsabgeordneter f\u00fcr Recklinghausen II in NRW und im Bundesvorstand der SPD zust\u00e4ndig f\u00fcr das Thema Mieterschutz. Stefanie Buchner-Joppich ist bei der Caritas in Schrobenhausen in der Wohnungsnotfallhilfe t\u00e4tig und beauftragt mit der sozialp\u00e4dagogischen Betreuung vor Ort.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cWohnen ist ja eigentlich ein Menschenrecht, aber gut zu wohnen wird immer schwieriger, vor allem in Deutschland und unserer Region. Wir haben eine zu gro\u00dfe Nachfrage, zu gro\u00dfen Zuzug und ein zu kleines Angebot. Trotz der Investitionen der Bundesregierung in den letzten Jahren fallen immer noch mehr Sozialwohnungen aus der Bindung als neue hinzukommen. Wir wollen in den n\u00e4chsten Jahren mindestens 100000 neue Sozialwohnungen j\u00e4hrlich schaffen. Es ist aber unser Ziel, mit gesetzlichen Regelungen die Mieten in den Griff zu bekommen \u2013 im Gegensatz zu FDP und Union, die alles auf dem Mietmarkt zulassen wollen. Ich m\u00f6chte mich zum Beispiel im Bundestag f\u00fcr ein Mietenmoratorium einsetzen. Das bedeutet, dass die Mieten nur noch in H\u00f6he der Inflationsraten erh\u00f6ht werden d\u00fcrfen, und w\u00fcrde Mieterinnen und Mietern sofort Sicherheit geben\u201d, so Andreas Mehltretter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Darauf folgte der erste Impuls von Stefanie Buchner-Joppich. Sie ist seit 2009 in der Schrobenhausener Caritas t\u00e4tig. \u201c 2014 beschloss der Stadtrat, es solle eine Wohnungslosenunterkunft und ein Sozialbau errichtet werden, aber seitdem wurden nur acht Wohnungen gebaut. Die Situation ist seitdem maximal angespannt. Was wenige nicht bedenken, ist, dass besonders Alleinerziehende, zum Beispiel nach einer Scheidung, solche Wohnungen brauchen, aber eben auch Alte, die einen barrierefreien Wohnraum suchen und keinen bezahlbaren finden k\u00f6nnen. Der Zensus 2011 hat uns gezeigt, dass es in Schrobenhausen viel Leerstand gab, da kam uns die Frage auf, warum die Eigent\u00fcmer denn nicht vermieten. Um dem entgegenzutreten, tritt die Stadt als Mietb\u00fcrge auf. Das hei\u00dft, dass die Stadt die Wohnungen anmietet und dann an Mieter untervermietet. Das schafft Sicherheit f\u00fcr die Mieter, dass das Geld flie\u00dft und sie nicht auf ihr Geld warten m\u00fcssen. Diese Aktion hat sich von Beginn an gut eingespielt. Aktuell begleiten wir 16 Parteien, beraten und betreuen Mieter, als auch Vermieter. Da der Wohnraum noch immer fehlt, wird das Projekt vom Stadtrat unterst\u00fctzt und weitergef\u00fchrt. Was besonders gut klappt, ist die Integration der Mieter. Anstatt von Sozialbaublocks sind die Wohnungen in der ganzen Stadt verteilt. Besser kann Integration nicht laufen!\u201d, so Buchner-Joppich. In Bayern wurde in den letzten zehn Jahren zwar viel mehr gebaut, besonders in letzter Zeit, jedoch sei das noch immer viel zu wenig, f\u00fcgte sie hinzu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Daraufhin sprach der Bundestagsabgeordnete Michael Gro\u00df: \u201cViele B\u00fcrger fordern, dass der Bund sich viel st\u00e4rker einsetzt, dabei muss man jedoch bedenken, dass er aufgrund unserer Verfassung nur mittelbar beteiligt ist. An sich ist er blo\u00df zust\u00e4ndig f\u00fcr das Mietrecht.\u201d Er kritisierte den Mangel an sozialem Wohnbau, \u201cnur zwei Millionen Wohnungen sind in der Hand kommunaler Wohnungstr\u00e4ger, dazu kommen zwei Millionen von Genossenschaften, die auch immer weniger bauen. Au\u00dferdem fordern die v. a. in St\u00e4dten oft auch eine hohe Beteiligung, sodass das nichts f\u00fcr Geringverdiener ist.\u201d Er forderte dazu auf, sich in dem Thema Mieten nicht nur auf die wichtigsten deutschen St\u00e4dte zu konzentrieren: \u201cMan muss nicht immer auf die Hotspots wie M\u00fcnchen oder Hamburg schauen. Auch in Dortmund, wo ich herkomme, geben viele \u00fcber 40% ihres Gehalts f\u00fcr die Miete aus\u201d, wobei er sich auf die neueste Studie der Hans-B\u00f6ckler-Stiftung, welche in den Medien gerade eine gro\u00dfe Rolle spielt, bezog. \u201cDas Problem ist also fl\u00e4chendeckend.\u201d Gro\u00df betonte aber auch die Fortschritte, welche die SPD bisher erm\u00f6glichte, wie zum Beispiel, dass sie die Mietpreisbremse auf den Weg gebracht haben. Als Aussicht f\u00fcr weitere zuk\u00fcnftige Schritte merkte er an, dass die SPD Staffel- und Indexmieten verbieten und alle Kommen \u00fcber 50.000 Einwohner zur Erstellung von Mietspiegeln verpflichten wolle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Anschluss folgte eine etwa einst\u00fcndige Diskussion mit dem Publikum. Hierbei wurde genauer auf das Schrobenhausener Konzept eingegangen und einige positive Aspekte dieser Herangehensweise hervorgehoben. Zum Beispiel, dass Vermieter die Stadt gern als untervermietenden Mieter haben, da sie so einen direkten Ansprechpartner bei Problemen haben. Au\u00dferdem wurde die Stigmatisierung sozialer Wohnbauten thematisiert. Denn diese werden in der Gesellschaft noch immer schlecht angesehen. \u201cDabei \u00fcbersehen viele, dass auch die Erzieherin im \u00f6rtlichen Kindergarten wom\u00f6glich soziale Unterst\u00fctzung ben\u00f6tigt, da sie sich mit ihrem Gehalt schlichtweg die Miete nicht eigenst\u00e4ndig leisten kann\u201d, so Buchner-Joppich.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abschlie\u00dfend ergriff Andreas Mehltretter das Wort: \u201cEs ist heute Abend deutlich geworden, dass es auch andere Ma\u00dfnahmen braucht, als nur auf mehr Neubauten zu setzen. Auch mit geringerem Aufwand kann solche Unterst\u00fctzung wie von der Schrobenhausener Wohnungsnotfallhilfe der Caritas gro\u00dfes bewirken und vielen Menschen helfen. Ich hoffe, dass wir diesen Herbst in eine Regierung ohne Union starten k\u00f6nnen, damit wir die n\u00f6tigen Schritte, um die Probleme der Mieter*innen unter Kontrolle zu bekommen, einleiten k\u00f6nnen.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach 1,5 Stunden, p\u00fcnktlich zum n\u00e4chsten Spiel der Fu\u00dfball-EM, war die Veranstaltung beendet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bericht zur Online-Veranstaltung am 16. Juni 2021 Als SPD im Bundeswahlkreis Freising-Pfaffenhofen-Schrobenhausen hatten wir zur Diskussion dar\u00fcber eingeladen, wie wir &hellip; <a href=\"https:\/\/www.andreas-mehltretter.de\/archiv\/2021\/06\/mit-dem-mietrecht-mieterinnen-staerken-und-entlasten\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Mit dem Mietrecht Mieter*innen st\u00e4rken und entlasten<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[7],"tags":[],"class_list":["post-1443","post","type-post","status-publish","format-standard","hentry","category-spd"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-json\/wp\/v2\/posts\/1443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-json\/wp\/v2\/comments?post=1443"}],"version-history":[{"count":1,"href":"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-json\/wp\/v2\/posts\/1443\/revisions"}],"predecessor-version":[{"id":1445,"href":"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-json\/wp\/v2\/posts\/1443\/revisions\/1445"}],"wp:attachment":[{"href":"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-json\/wp\/v2\/media?parent=1443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-json\/wp\/v2\/categories?post=1443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-json\/wp\/v2\/tags?post=1443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}