{"id":785,"date":"2017-11-24T14:17:54","date_gmt":"2017-11-24T13:17:54","guid":{"rendered":"https:\/\/www.andreas-mehltretter.de\/wp\/?p=785"},"modified":"2017-12-31T15:55:08","modified_gmt":"2017-12-31T14:55:08","slug":"nach-dem-jamaika-kater-wie-verhindern-wir-eine-erneute-groko","status":"publish","type":"post","link":"https:\/\/www.andreas-mehltretter.de\/archiv\/2017\/11\/nach-dem-jamaika-kater-wie-verhindern-wir-eine-erneute-groko\/","title":{"rendered":"Nach dem Jamaika-Kater: Wie verhindern wir eine erneute GroKo?"},"content":{"rendered":"<p>Ich finde es ja sehr spannend, wie viele Kommentare von Genoss*innen gegen eine neue gro\u00dfe Koalition in meinen Facebook- und Twitter-Timelines auftauchen. Die Intention dahinter halte ich f\u00fcr gut und ehrenwert, aber f\u00fcr mich ist es trotzdem erschreckend, wie wenige sich dar\u00fcber Gedanken zu machen scheinen, wie es ohne gro\u00dfe Koalition weitergehen soll. #nogroko ist als allgemeine Einstellung ohne Zweifel das einzig richtige, aber es ist in der aktuellen Situation als Handlungsempfehlung viel zu wenig und somit unbrauchbar. Der Druck auf die SPD ist diese Woche erst dadurch entstanden, weil der Parteivorstand am Montag Vormittag beschlossen hat, die gro\u00dfe Koalition kategorisch auszuschlie\u00dfen \u2013 ohne aber irgendeinen Ausweg oder eine Handlungsoption f\u00fcr die SPD vorzuschlagen.<\/p>\n<p>Wir m\u00fcssen jetzt so ehrlich sein und uns die Alternativen anschauen, die der SPD bleiben: Eine der drei Alternativen GroKo, Minderheitsregierung oder Neuwahlen wird letztlich umgesetzt werden, und wenn wir die GroKo verhindern wollen, m\u00fcssen wir aktiv auf eine Alternative hinarbeiten \u2013 wenn wir uns nicht f\u00fcr Neuwahlen oder eine Minderheitsregierung einsetzen, wird es zwangsweise auf eine gro\u00dfe Koalition hinauslaufen, auch wenn wir das f\u00fcr die schlechteste Option halten sollten.<\/p>\n<p>Was bleibt uns also? Neuwahlen? Mir ist vollkommen schleierhaft, warum sich die SPD in der aktuellen politischen Situation und angesichts ihres eigenen Zustands aktiv f\u00fcr Neuwahlen einsetzen kann. Wir haben keinen unumstrittenen Kanzlerkandidaten, wir haben noch keinen eingearbeiteten Generalsekret\u00e4r, wir haben keine Bundesgesch\u00e4ftsf\u00fchrerin \u2013 und wir haben in diesem Jahr gesehen, wie gut eine Kampa im Willy-Brandt-Haus funktioniert, wenn <em>beste<\/em> Voraussetzungen herrschen, also wird eine Kampagne zum jetzigen Zeitpunkt sicher nicht besser ausfallen. Au\u00dferdem sind wir beim Erneuerungsmarathon bisher wenn \u00fcberhaupt einen knappen Kilometer vorangekommen, das hei\u00dft es gibt auch inhaltlich \u00fcberhaupt keinen Grund, jetzt pl\u00f6tzlich SPD zu w\u00e4hlen, wenn man das nicht auch schon im September getan hat.<br \/>\nDass Neuwahlen aber \u00fcberhaupt einen Sinn ergeben, m\u00fcssen sie ja dazu f\u00fchren, dass sich neue potentielle Koalitionsoptionen ergeben: F\u00fcr Rot-Rot-Gr\u00fcn braucht es eine W\u00e4hlerwanderung von rund 9 Prozent, f\u00fcr Schwarz-Gr\u00fcn von rund 6 Prozent und f\u00fcr Schwarz-Gelb rund 4 Prozent. Wo sollen die R2G-W\u00e4hler pl\u00f6tzlich, innerhalb weniger Monate und ohne bisherige Umfrage-Anzeichen daf\u00fcr, herkommen? Oder w\u00fcnschen wir uns Mehrheiten f\u00fcr Schwarz-Gr\u00fcn oder Schwarz-Gelb, die wohl nur zustande kommen, wenn die SPD noch weiter verliert? Nat\u00fcrlich sind Aufholjagden m\u00f6glich, nat\u00fcrlich k\u00f6nnen sich Stimmungen schnell \u00e4ndern, aber daf\u00fcr braucht es trotzdem Gr\u00fcnde und gute Pl\u00e4ne, und die sind f\u00fcr mich beide nicht sichtbar. Die bei weitem wahrscheinlichste Konsequenz bei Neuwahlen ist also, dass wir vor der gleichen Situation stehen wie jetzt, sprich: GroKo oder Minderheitsregierung.<\/p>\n<p>Was bleibt also, wenn wir keine Groko wollen? F\u00fcr mich spricht alles daf\u00fcr, jetzt eine schwarz-gr\u00fcne Minderheitsregierung zu forcieren. Das w\u00fcrde dem parlamentarischen Diskurs gut tun, wenn Politik tats\u00e4chlich im Bundestag diskutiert und ausgehandelt w\u00fcrde, der SPD den Vorwurf der Umfallerei (wenn GroKo) oder Verantwortungslosigkeit (wenn Neuwahlen) ersparen \u2013 und sogar dazu f\u00fchren, dass die SPD gro\u00dfen politischen Gestaltungsspielraum erh\u00e4lt, ohne daf\u00fcr die Oppositionsrolle v\u00f6llig und die Chance zur Erneuerung aufgeben zu m\u00fcssen.<\/p>\n<p>Wir m\u00fcssen uns aber klar werden, dass eine solche L\u00f6sung sehr wahrscheinlich nicht zustande kommen wird, wenn wir als SPD, und wir als Jusos innerhalb der SPD, nicht aktiv darauf hin arbeiten, sprich ein Konzept aufstellen, unter welchen Bedingungen wir uns eine schwarz-gr\u00fcne Regierung vorstellen k\u00f6nnten. Nur das Bekenntnis zu #nogroko hilft uns nicht weiter, und nur wenn wir jetzt innerparteilich andere, gangbare Wege aufzeigen, werden wir es auch schaffen, eine weitere gro\u00dfe Koalition zu verhindern.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich finde es ja sehr spannend, wie viele Kommentare von Genoss*innen gegen eine neue gro\u00dfe Koalition in meinen Facebook- und &hellip; <a href=\"https:\/\/www.andreas-mehltretter.de\/archiv\/2017\/11\/nach-dem-jamaika-kater-wie-verhindern-wir-eine-erneute-groko\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Nach dem Jamaika-Kater: Wie verhindern wir eine erneute GroKo?<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2,7],"tags":[],"class_list":["post-785","post","type-post","status-publish","format-standard","hentry","category-politisches","category-spd"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-json\/wp\/v2\/posts\/785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-json\/wp\/v2\/comments?post=785"}],"version-history":[{"count":2,"href":"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-json\/wp\/v2\/posts\/785\/revisions"}],"predecessor-version":[{"id":787,"href":"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-json\/wp\/v2\/posts\/785\/revisions\/787"}],"wp:attachment":[{"href":"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-json\/wp\/v2\/media?parent=785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-json\/wp\/v2\/categories?post=785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.andreas-mehltretter.de\/archiv\/wp-json\/wp\/v2\/tags?post=785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}